{"id":3392,"date":"2025-05-08T12:49:12","date_gmt":"2025-05-08T12:49:12","guid":{"rendered":"https:\/\/www.jk7spawellness.com\/skincare-retreat-buchen\/"},"modified":"2026-01-27T01:36:18","modified_gmt":"2026-01-27T01:36:18","slug":"skincare-retreat-buchen","status":"publish","type":"page","link":"https:\/\/www.jk7spawellness.com\/de\/skincare-retreat-buchen\/","title":{"rendered":"Skincare Retreat buchen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3392\" class=\"elementor elementor-3392 elementor-2695\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23d401d e-flex e-con-boxed e-con e-parent\" data-id=\"23d401d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9164a9 elementor-widget elementor-widget-heading\" data-id=\"f9164a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Buchen Sie Ihr <br>Skincare-Retreat<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e2e9eb e-con-full e-flex e-con e-child\" data-id=\"5e2e9eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85a9ff6 e-add-animated e-add-animated-liveyes elementor-widget elementor-widget-text-editor\" data-id=\"85a9ff6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;e_animations_enable&quot;:&quot;yes&quot;,&quot;alpha_transition_liveanim&quot;:&quot;alphaopacity&quot;,&quot;vertical_transition_liveanim&quot;:&quot;tobottom&quot;,&quot;entrance_amount_liveanim&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.05,&quot;sizes&quot;:[]},&quot;entrance_speed_liveanim&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;entrance_delay_liveanim&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;equation_entrance_animation_liveanim&quot;:&quot;power3&quot;,&quot;ease_entrance_animation_liveanim&quot;:&quot;inOut&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-add-animations-entrance\">\t\t\t\t<p><strong>N\u00e4chste Termine:<\/strong><\/p>\n<p>Freitag, 22. Mai 2026 bis Mittwoch, 27. Mai 2026 (5 N\u00e4chte)<\/p>\n<p>Freitag, 18. September 2026 bis Mittwoch, 23. September 2026 (5 \u00dcbernachtungen)<\/p>\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73d565f elementor-widget elementor-widget-Single Calendar\" data-id=\"73d565f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Single Calendar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpbs-main-wrapper wpbs-main-wrapper-calendar-3 wpbs-main-wrapper-form-2\"><a class=\"wpbs-visually-hidden wpbs-skip-to-content-link\" title=\"Skip Booking Form\" href=\"#wpbs-booking-form-end\">Skip Booking Form<\/a><div class=\"wpbs-container wpbs-enable-hover wpbs-calendar-3 \" data-id=\"3\" data-show_title=\"0\" data-months_to_show=\"2\" data-start_weekday=\"1\" data-show_legend=\"1\" data-legend_position=\"side\" data-show_button_navigation=\"1\" data-show_selector_navigation=\"1\" data-show_week_numbers=\"0\" data-current_year=\"2026\" data-current_month=\"9\" data-jump_months=\"0\" data-highlight_today=\"0\" data-history=\"1\" data-show_tooltip=\"1\" data-show_prices=\"0\" data-language=\"de\" data-min_width=\"200\" data-max_width=\"380\" data-start_date=\"0\" data-end_date=\"0\" data-changeover_start=\"0\" data-changeover_end=\"0\" data-currency=\"USD\" data-form_position=\"bottom\" data-current_date=\"1784073600000\" data-show_first_available_date=\"0\" ><div class=\"wpbs-calendars-wrapper wpbs-legend-position-side\"><div class=\"wpbs-legend\"><div class=\"wpbs-legend-item\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-9\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><span class=wpbs-legend-item-name>Verf\u00fcgbar<\/span><\/div><div class=\"wpbs-legend-item\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><span class=wpbs-legend-item-name>Gebucht<\/span><\/div><\/div><div class=\"wpbs-calendars\"><div class=\"wpbs-calendar wpbs-calendar-month-9 wpbs-calendar-year-2026 \"><div class=\"wpbs-calendar-header wpbs-heading\"><div class=\"wpbs-calendar-header-navigation\"><button class=\"wpbs-prev\" aria-label=\"Navigate to previous month\"><span class=\"wpbs-arrow\"><\/span><\/button><div class=\"wpbs-select-container\"><select name=\"wpbs-month-selector-dropdown\" aria-label=\"Calendar month navigation\"><option value=\"1781481600\" >Juni 2026<\/option><option value=\"1784073600\" >Juli 2026<\/option><option value=\"1786752000\" >August 2026<\/option><option value=\"1789430400\"  selected='selected'>September 2026<\/option><option value=\"1792022400\" >Oktober 2026<\/option><option value=\"1794700800\" >November 2026<\/option><option value=\"1797292800\" >Dezember 2026<\/option><option value=\"1799971200\" >Januar 2027<\/option><option value=\"1802649600\" >Februar 2027<\/option><option value=\"1805068800\" >M\u00e4rz 2027<\/option><option value=\"1807747200\" >April 2027<\/option><option value=\"1810339200\" >Mai 2027<\/option><option value=\"1813017600\" >Juni 2027<\/option><option value=\"1815609600\" >Juli 2027<\/option><option value=\"1818288000\" >August 2027<\/option><option value=\"1820966400\" >September 2027<\/option><\/select><\/div><\/div><\/div><div class=\"wpbs-calendar-wrapper\"><table><thead><tr><th>M<\/th><th>D<\/th><th>M<\/th><th>D<\/th><th>F<\/th><th>S<\/th><th>S<\/th><\/tr><\/thead><tbody><tr><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"0\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"1\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">1<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"2\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">2<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"3\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">3<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"4\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">4<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"5\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">5<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"6\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">6<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"7\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">7<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"8\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">8<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"9\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">9<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"10\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">10<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"11\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">11<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"12\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">12<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"13\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">13<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"14\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">14<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"15\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">15<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"16\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">16<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"17\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">17<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-9   wpbs-is-bookable \" data-year=\"2026\" data-month=\"9\" data-day=\"18\" data-price=\"0\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-9\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">18<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-9   wpbs-is-bookable \" data-year=\"2026\" data-month=\"9\" data-day=\"19\" data-price=\"0\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-9\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">19<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-9   wpbs-is-bookable \" data-year=\"2026\" data-month=\"9\" data-day=\"20\" data-price=\"0\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-9\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">20<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-9   wpbs-is-bookable \" data-year=\"2026\" data-month=\"9\" data-day=\"21\" data-price=\"0\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-9\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">21<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-9   wpbs-is-bookable \" data-year=\"2026\" data-month=\"9\" data-day=\"22\" data-price=\"0\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-9\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">22<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-9   wpbs-is-bookable \" data-year=\"2026\" data-month=\"9\" data-day=\"23\" data-price=\"0\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-9\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">23<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"24\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">24<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"25\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">25<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"26\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">26<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"27\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">27<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"28\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">28<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"29\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">29<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"9\" data-day=\"30\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">30<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"0\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"0\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"0\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"0\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/div><div class=\"wpbs-calendar wpbs-calendar-month-10 wpbs-calendar-year-2026 \"><div class=\"wpbs-calendar-header wpbs-heading\"><div class=\"wpbs-calendar-header-navigation\"><span class=\"wpbs-calendar-header-navigation-month-name\">Oktober 2026<\/span><button class=\"wpbs-next\" aria-label=\"Navigate to next month\"><span class=\"wpbs-arrow\"><\/span><\/button><\/div><\/div><div class=\"wpbs-calendar-wrapper\"><table><thead><tr><th>M<\/th><th>D<\/th><th>M<\/th><th>D<\/th><th>F<\/th><th>S<\/th><th>S<\/th><\/tr><\/thead><tbody><tr><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"0\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"0\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"0\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"1\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">1<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"2\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">2<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"3\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">3<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"4\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">4<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"5\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">5<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"6\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">6<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"7\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">7<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"8\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">8<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"9\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">9<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"10\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">10<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"11\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">11<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"12\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">12<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"13\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">13<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"14\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">14<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"15\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">15<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"16\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">16<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"17\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">17<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"18\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">18<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"19\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">19<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"20\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">20<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"21\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">21<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"22\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">22<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"23\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">23<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"24\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">24<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"25\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">25<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"26\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">26<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"27\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">27<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"28\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">28<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"29\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">29<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"30\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">30<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-10    \" data-year=\"2026\" data-month=\"10\" data-day=\"31\" data-price=\"0\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-10\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">31<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"0\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><style>.wpbs-container.wpbs-calendar-3 .wpbs-legend-item-icon-9 div:first-of-type { background-color: #bbe698 !important; }.wpbs-container.wpbs-calendar-3 .wpbs-legend-item-icon-9 div:nth-of-type(2) { background-color: transparent !important; }.wpbs-container.wpbs-calendar-3 .wpbs-legend-item-icon-9 div:first-of-type svg { fill: #bbe698 !important; }.wpbs-container.wpbs-calendar-3 .wpbs-legend-item-icon-9 div:nth-of-type(2) svg { fill: transparent !important; }.wpbs-ical-changeover .wpbs-legend-item-icon:after {background-color: #bbe698;}.wpbs-container.wpbs-calendar-3 .wpbs-legend-item-icon-10 div:first-of-type { background-color: #ebe4d9 !important; }.wpbs-container.wpbs-calendar-3 .wpbs-legend-item-icon-10 div:nth-of-type(2) { background-color: transparent !important; }.wpbs-container.wpbs-calendar-3 .wpbs-legend-item-icon-10 div:first-of-type svg { fill: #ebe4d9 !important; }.wpbs-container.wpbs-calendar-3 .wpbs-legend-item-icon-10 div:nth-of-type(2) svg { fill: transparent !important; }.wpbs-container.wpbs-calendar-3 .wpbs-legend-item-icon-today div:first-of-type { background-color: rgba( 33,150,243, .9 ) !important; }.wpbs-container.wpbs-calendar-3 .wpbs-legend-item-icon-0 div:first-of-type { background-color: #e1e1e1 !important; }.wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-enable-hover .wpbs-is-bookable:hover:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon div:first-of-type, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-hover:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon div:first-of-type, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-hover.wpbs-selected-first.wpbs-selected-last .wpbs-legend-item-icon div:first-of-type { background-color: #e6a7fd !important; }.wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-enable-hover .wpbs-is-bookable:hover:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon[data-type=\"split\"] div svg, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-hover:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon[data-type=\"split\"] div svg, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-legend-item-icon .wpbs-legend-icon-select svg { fill: #e6a7fd !important; }.wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-selected:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon div:first-of-type, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-selected.wpbs-selected-first.wpbs-selected-last .wpbs-legend-item-icon div:first-of-type, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-enable-hover .wpbs-date-selected:hover:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon div:first-of-type { background-color: #dc85fc !important; }.wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-selected:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon[data-type=\"split\"] div svg, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-enable-hover .wpbs-date-selected:hover:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon[data-type=\"split\"] div svg, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-selected .wpbs-legend-item-icon .wpbs-legend-icon-select svg { fill: #dc85fc !important; }.wpbs-date-today:not(.wpbs-date-hover):not(.wpbs-date-selected) .wpbs-legend-item-icon {border: 4px solid #e6a7fd !important;}<\/style><div class=\"wpbs-container-loaded\" data-just-loaded=\"1\"><\/div><\/div><form method=\"post\" novalidate=\"novalidate\" action=\"#\" id=\"wpbs-form-2\" class=\"wpbs-form-container wpbs-form-2\" data-id=\"2\" data-minimum_days=\"0\" data-maximum_days=\"0\" data-booking_start_day=\"0\" data-booking_end_day=\"0\" data-selection_type=\"multiple\" data-selection_style=\"split\" data-language=\"de\" data-auto_pending=\"1\" data-show_date_selection=\"0\" data-currency=\"USD\" ><div class=\"wpbs-form-fields\"><div class=\"wpbs-form-field wpbs-form-field-text wpbs-form-field-2-1 wpbs-field-layout-left wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-2-1-9a0be53d\">Vorname<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"text\"\r\n            name=\"wpbs-input-2-1\"\r\n            id=\"wpbs-form-field-input-2-1-9a0be53d\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-text wpbs-form-field-2-2 wpbs-field-layout-right wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-2-2-9a0be53d\">Nachname<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"text\"\r\n            name=\"wpbs-input-2-2\"\r\n            id=\"wpbs-form-field-input-2-2-9a0be53d\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-text wpbs-form-field-2-3 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-2-3-9a0be53d\">Adresse<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"text\"\r\n            name=\"wpbs-input-2-3\"\r\n            id=\"wpbs-form-field-input-2-3-9a0be53d\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-text wpbs-form-field-2-4 wpbs-field-layout-left wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-2-4-9a0be53d\">PLZ<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"text\"\r\n            name=\"wpbs-input-2-4\"\r\n            id=\"wpbs-form-field-input-2-4-9a0be53d\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-text wpbs-form-field-2-5 wpbs-field-layout-right wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-2-5-9a0be53d\">Ort<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"text\"\r\n            name=\"wpbs-input-2-5\"\r\n            id=\"wpbs-form-field-input-2-5-9a0be53d\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-text wpbs-form-field-2-18 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-2-18-9a0be53d\">Land<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"text\"\r\n            name=\"wpbs-input-2-18\"\r\n            id=\"wpbs-form-field-input-2-18-9a0be53d\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-phone wpbs-form-field-2-6 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-2-6-9a0be53d\">Telefonnummer<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"text\"\r\n            name=\"wpbs-input-2-6\"\r\n            id=\"wpbs-form-field-input-2-6-9a0be53d\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            data-error=\"Ung\u00fcltige Telefonnummer.\"\r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-email wpbs-form-field-2-7 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-2-7-9a0be53d\">E-Mail<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"email\"\r\n            name=\"wpbs-input-2-7\"\r\n            id=\"wpbs-form-field-input-2-7-9a0be53d\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-number wpbs-form-field-2-19 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-2-19-9a0be53d\">Anzahl Personen<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"number\"\r\n            step=\"1\"\r\n            data-decimals=\"0\"\r\n            min=\"1\"\r\n            max=\"8\"\r\n            name=\"wpbs-input-2-19\"\r\n            id=\"wpbs-form-field-input-2-19-9a0be53d\"\r\n            value=\"\"\r\n            data-value=\"\"\r\n            placeholder=\"\"\r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-dropdown wpbs-form-field-2-15 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-2-15-9a0be53d\">Welches Zimmer w\u00fcnscht du dir?<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><select\r\n            name=\"wpbs-input-2-15\"\r\n            id=\"wpbs-form-field-input-2-15-9a0be53d\"\r\n            \r\n        ><option  value=\"spielt keine Rolle..\">spielt keine Rolle..<\/option><option  value=\"Green Suite Heart Chakra - Love and Balance\">Green Suite Heart Chakra - Love and Balance<\/option><option  value=\"Blue Suite Throat Chakra - Communication\">Blue Suite Throat Chakra - Communication<\/option><option  value=\"Magenta Suite Crown Chakra - Spirituality\">Magenta Suite Crown Chakra - Spirituality<\/option><option  value=\"Indigo Suite Third Eye Chakra - Perception\">Indigo Suite Third Eye Chakra - Perception<\/option><\/select><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-dropdown wpbs-form-field-2-16 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-2-16-9a0be53d\">Belegung:<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><select\r\n            name=\"wpbs-input-2-16\"\r\n            id=\"wpbs-form-field-input-2-16-9a0be53d\"\r\n            \r\n        ><option  value=\"Einzelbelegung ab \u20ac10,125 pro Person\">Einzelbelegung ab \u20ac10,125 pro Person<\/option><option  value=\"Doppelbelegung ab \u20ac9,125 pro Person\">Doppelbelegung ab \u20ac9,125 pro Person<\/option><\/select><\/div><\/div><input class=\"wpbs-google-recaptcha-v3\" type=\"hidden\" name=\"g-recaptcha-response\" id=\"wpbs-google-recaptcha-v3-2-9a0be53d\" data-sitekey=\"6Ld8ORorAAAAAAl8WyxQDQTcJm4D_vT8cbI47clR\"><\/div><input type=\"hidden\" name=\"wpbs-upload-token\" value=\"388e875f\"><input type=\"hidden\" name=\"wpbs-return-url\" value=\"https:\/\/www.jk7spawellness.com\/de\/wp-json\/wp\/v2\/pages\/3392\"><input type=\"hidden\" name=\"wpbs-post-id\" value=\"3392\"><div class=\"wpbs-form-field wpbs-form-submit-button\"><button type=\"submit\" class=\"\" id=\"wpbs-form-submit-2\">Anfrage absenden<\/button><\/div><style><\/style><\/form><span class=\"wpbs-visually-hidden\" id=\"wpbs-booking-form-end\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Buchen Sie Ihr Skincare-Retreat N\u00e4chste Termine: Freitag, 22. Mai 2026 bis Mittwoch, 27. Mai 2026 (5 N\u00e4chte) Freitag, 18. September 2026 bis Mittwoch, 23. September 2026 (5 \u00dcbernachtungen) Skip Booking FormAvailableBookedFebruary 2026March 2026April 2026May 2026June 2026July 2026August 2026September 2026October 2026November 2026December 2026January 2027February 2027March 2027April 2027May 2027 M T W T F S S 1 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"class_list":["post-3392","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Buchen Sie Ihr Skincare-Retreat | JK7\u00ae Spa &amp; Wellness<\/title>\n<meta name=\"description\" content=\"Ihre Verwandlung: 5 N\u00e4chte Skincare-Retreat in \u00d6sterreich mit Bio-JK7\u00ae-Treatments, Yoga &amp; Meditation in einem exklusiven, privaten Refugium genie\u00dfen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jk7spawellness.com\/de\/skincare-retreat-buchen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buchen Sie Ihr Skincare-Retreat | JK7\u00ae Spa &amp; Wellness\" \/>\n<meta property=\"og:description\" content=\"Ihre Verwandlung: 5 N\u00e4chte Skincare-Retreat in \u00d6sterreich mit Bio-JK7\u00ae-Treatments, Yoga &amp; Meditation in einem exklusiven, privaten Refugium genie\u00dfen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jk7spawellness.com\/de\/skincare-retreat-buchen\/\" \/>\n<meta property=\"og:site_name\" content=\"Luxury Wellness Retreat in Austria | JK7\u00ae Spa &amp; Skincare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T01:36:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jk7spawellness.com\\\/de\\\/skincare-retreat-buchen\\\/\",\"url\":\"https:\\\/\\\/www.jk7spawellness.com\\\/de\\\/skincare-retreat-buchen\\\/\",\"name\":\"Buchen Sie Ihr Skincare-Retreat | JK7\u00ae Spa & Wellness\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jk7spawellness.com\\\/de\\\/#website\"},\"datePublished\":\"2025-05-08T12:49:12+00:00\",\"dateModified\":\"2026-01-27T01:36:18+00:00\",\"description\":\"Ihre Verwandlung: 5 N\u00e4chte Skincare-Retreat in \u00d6sterreich mit Bio-JK7\u00ae-Treatments, Yoga & Meditation in einem exklusiven, privaten Refugium genie\u00dfen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jk7spawellness.com\\\/de\\\/skincare-retreat-buchen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jk7spawellness.com\\\/de\\\/skincare-retreat-buchen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jk7spawellness.com\\\/de\\\/skincare-retreat-buchen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.jk7spawellness.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Skincare Retreat buchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jk7spawellness.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.jk7spawellness.com\\\/de\\\/\",\"name\":\"Luxury Wellness Retreat in Austria | JK7\u00ae Spa &amp; Skincare\",\"description\":\"Luxury Wellness Retreat in Austria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jk7spawellness.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buchen Sie Ihr Skincare-Retreat | JK7\u00ae Spa & Wellness","description":"Ihre Verwandlung: 5 N\u00e4chte Skincare-Retreat in \u00d6sterreich mit Bio-JK7\u00ae-Treatments, Yoga & Meditation in einem exklusiven, privaten Refugium genie\u00dfen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jk7spawellness.com\/de\/skincare-retreat-buchen\/","og_locale":"de_DE","og_type":"article","og_title":"Buchen Sie Ihr Skincare-Retreat | JK7\u00ae Spa & Wellness","og_description":"Ihre Verwandlung: 5 N\u00e4chte Skincare-Retreat in \u00d6sterreich mit Bio-JK7\u00ae-Treatments, Yoga & Meditation in einem exklusiven, privaten Refugium genie\u00dfen.","og_url":"https:\/\/www.jk7spawellness.com\/de\/skincare-retreat-buchen\/","og_site_name":"Luxury Wellness Retreat in Austria | JK7\u00ae Spa &amp; Skincare","article_modified_time":"2026-01-27T01:36:18+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jk7spawellness.com\/de\/skincare-retreat-buchen\/","url":"https:\/\/www.jk7spawellness.com\/de\/skincare-retreat-buchen\/","name":"Buchen Sie Ihr Skincare-Retreat | JK7\u00ae Spa & Wellness","isPartOf":{"@id":"https:\/\/www.jk7spawellness.com\/de\/#website"},"datePublished":"2025-05-08T12:49:12+00:00","dateModified":"2026-01-27T01:36:18+00:00","description":"Ihre Verwandlung: 5 N\u00e4chte Skincare-Retreat in \u00d6sterreich mit Bio-JK7\u00ae-Treatments, Yoga & Meditation in einem exklusiven, privaten Refugium genie\u00dfen.","breadcrumb":{"@id":"https:\/\/www.jk7spawellness.com\/de\/skincare-retreat-buchen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jk7spawellness.com\/de\/skincare-retreat-buchen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jk7spawellness.com\/de\/skincare-retreat-buchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.jk7spawellness.com\/de\/"},{"@type":"ListItem","position":2,"name":"Skincare Retreat buchen"}]},{"@type":"WebSite","@id":"https:\/\/www.jk7spawellness.com\/de\/#website","url":"https:\/\/www.jk7spawellness.com\/de\/","name":"Luxury Wellness Retreat in Austria | JK7\u00ae Spa &amp; Skincare","description":"Luxury Wellness Retreat in Austria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jk7spawellness.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.jk7spawellness.com\/de\/wp-json\/wp\/v2\/pages\/3392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jk7spawellness.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.jk7spawellness.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.jk7spawellness.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jk7spawellness.com\/de\/wp-json\/wp\/v2\/comments?post=3392"}],"version-history":[{"count":7,"href":"https:\/\/www.jk7spawellness.com\/de\/wp-json\/wp\/v2\/pages\/3392\/revisions"}],"predecessor-version":[{"id":3837,"href":"https:\/\/www.jk7spawellness.com\/de\/wp-json\/wp\/v2\/pages\/3392\/revisions\/3837"}],"wp:attachment":[{"href":"https:\/\/www.jk7spawellness.com\/de\/wp-json\/wp\/v2\/media?parent=3392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}